{"id":1979,"date":"2023-03-04T16:02:47","date_gmt":"2023-03-04T12:02:47","guid":{"rendered":"https:\/\/innovator.md\/?page_id=1979"},"modified":"2023-05-30T18:23:21","modified_gmt":"2023-05-30T14:23:21","slug":"partners","status":"publish","type":"page","link":"https:\/\/innovator.md\/ro\/partners\/","title":{"rendered":"Parteneri"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1979\" class=\"elementor elementor-1979\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-310573cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"310573cd\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7695d44f\" data-id=\"7695d44f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4675142f elementor-widget elementor-widget-heading\" data-id=\"4675142f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Parteneri<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a091851 elementor-icon-list--layout-inline elementor-align-center elementor-mobile-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2a091851\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Acas\u0103<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Parteneri<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d3babd1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d3babd1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24a315c0\" data-id=\"24a315c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79bb7396 elementor-widget elementor-widget-heading\" data-id=\"79bb7396\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our Partners<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecf1485 elementor-widget elementor-widget-heading\" data-id=\"ecf1485\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">World's leading manufacturers\nrepresentatives in Georgia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57ffa9da elementor-widget elementor-widget-text-editor\" data-id=\"57ffa9da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Innovator is the official representative of the world\u2019s leading manufacturers, with the legal right to distribute their products.<\/p><p>We offer the product and service you want on the best terms; in addition, we are always ready to introduce and provide you with the latest approaches in the direction of broadcasting equipment;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2cd5e4de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2cd5e4de\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19b8be1b\" data-id=\"19b8be1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4233bc1 elementor-widget elementor-widget-spacer\" data-id=\"4233bc1\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-963db6d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"963db6d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9a2989e\" data-id=\"9a2989e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-88849b0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88849b0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-38f7345\" data-id=\"38f7345\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e39a46a elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e39a46a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a937d6e\" data-id=\"a937d6e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f30b84 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"6f30b84\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/innovator.md\/ro\/?page_id=2128\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/sony.png\" class=\"attachment-full size-full wp-image-1994\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/sony.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/sony-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/sony-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/sony-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1741b3a\" data-id=\"1741b3a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-877a47f elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"877a47f\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/vsn.png\" class=\"attachment-full size-full wp-image-2039\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/vsn.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/vsn-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/vsn-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/vsn-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d321e28\" data-id=\"d321e28\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f3e45b elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"8f3e45b\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/live-u.png\" class=\"attachment-full size-full wp-image-2003\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/live-u.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/live-u-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/live-u-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/live-u-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-0f2b12a\" data-id=\"0f2b12a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac42a25 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"ac42a25\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/arri.png\" class=\"attachment-full size-full wp-image-2011\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/arri.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/arri-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/arri-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/arri-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6f50439 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f50439\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-46bf8b0\" data-id=\"46bf8b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dedcd9e elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"dedcd9e\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/panasonic.png\" class=\"attachment-full size-full wp-image-2031\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/panasonic.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/panasonic-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/panasonic-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/panasonic-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-768273d\" data-id=\"768273d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8b2d88 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"e8b2d88\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/blacjmagic.png\" class=\"attachment-full size-full wp-image-2012\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/blacjmagic.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/blacjmagic-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/blacjmagic-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/blacjmagic-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3ebe6b4\" data-id=\"3ebe6b4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c83cf47 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"c83cf47\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/panasonic.png\" class=\"attachment-full size-full wp-image-2031\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/panasonic.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/panasonic-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/panasonic-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/panasonic-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-28a3efd\" data-id=\"28a3efd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4ad564 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"a4ad564\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/ross.png\" class=\"attachment-full size-full wp-image-2032\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/ross.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/ross-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/ross-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/ross-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-454d762 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"454d762\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5100cfb\" data-id=\"5100cfb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce7b6fb elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"ce7b6fb\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/manfrotto.png\" class=\"attachment-full size-full wp-image-2029\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/manfrotto.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/manfrotto-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/manfrotto-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/manfrotto-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ad6dee6\" data-id=\"ad6dee6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49ee0c5 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"49ee0c5\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/jvc.png\" class=\"attachment-full size-full wp-image-2024\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/jvc.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/jvc-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/jvc-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/jvc-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-bef9f4b\" data-id=\"bef9f4b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-816a80b elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"816a80b\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/canon.png\" class=\"attachment-full size-full wp-image-2018\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/canon.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/canon-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/canon-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/canon-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4cf9907\" data-id=\"4cf9907\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1e1765 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"b1e1765\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/datavideo.png\" class=\"attachment-full size-full wp-image-2019\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/datavideo.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/datavideo-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/datavideo-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/datavideo-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-588b00c elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"588b00c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-20aeb41\" data-id=\"20aeb41\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a70a35b elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"a70a35b\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/broadstream.png\" class=\"attachment-full size-full wp-image-2015\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/broadstream.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/broadstream-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/broadstream-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/broadstream-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3b8a857\" data-id=\"3b8a857\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eec1de0 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"eec1de0\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/canford.png\" class=\"attachment-full size-full wp-image-2017\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/canford.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/canford-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/canford-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/canford-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-685799c\" data-id=\"685799c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56d41ff elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"56d41ff\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/fuji.png\" class=\"attachment-full size-full wp-image-2022\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/fuji.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/fuji-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/fuji-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/fuji-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6abaa30\" data-id=\"6abaa30\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45b8d16 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"45b8d16\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/ikan.png\" class=\"attachment-full size-full wp-image-2023\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/ikan.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/ikan-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/ikan-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/ikan-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eb80437 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb80437\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2db6c67\" data-id=\"2db6c67\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f1e4f7 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"7f1e4f7\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/canare.png\" class=\"attachment-full size-full wp-image-2016\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/canare.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/canare-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/canare-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/canare-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e8a0ab7\" data-id=\"e8a0ab7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b91601 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"9b91601\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/download-1.png\" class=\"attachment-full size-full wp-image-2020\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/download-1.png 225w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/download-1-150x150.png 150w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-32e2ee8\" data-id=\"32e2ee8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1129d6e elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"1129d6e\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/kramer.png\" class=\"attachment-full size-full wp-image-2025\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/kramer.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/kramer-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/kramer-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/kramer-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a576858\" data-id=\"a576858\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf79228 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"cf79228\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/lynx-technik-ag-vector-logo.png\" class=\"attachment-full size-full wp-image-2028\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/lynx-technik-ag-vector-logo.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/lynx-technik-ag-vector-logo-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/lynx-technik-ag-vector-logo-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/lynx-technik-ag-vector-logo-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-28d6a7a elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28d6a7a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-195374f\" data-id=\"195374f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-366ddc0 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"366ddc0\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/egripment.png\" class=\"attachment-full size-full wp-image-2021\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/egripment.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/egripment-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/egripment-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/egripment-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2c375c0\" data-id=\"2c375c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c23d19b elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"c23d19b\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"892\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/masterclock.png\" class=\"attachment-full size-full wp-image-2030\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/masterclock.png 1280w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/masterclock-300x209.png 300w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/masterclock-1024x714.png 1024w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/03\/masterclock-768x535.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a1f1069\" data-id=\"a1f1069\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-9df3fa5\" data-id=\"9df3fa5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab986f9 elementor-widget elementor-widget-heading\" data-id=\"ab986f9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Our Process<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08820bd elementor-widget elementor-widget-heading\" data-id=\"08820bd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">How We Works<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c70462c elementor-widget elementor-widget-text-editor\" data-id=\"c70462c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Our main goal is to understand and deliver the best video\/audio broadcasting solutions for you.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c55db01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c55db01\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1d7bfc3\" data-id=\"1d7bfc3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77f6815 elementor-widget__width-initial elementor-absolute elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"77f6815\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"90\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/02\/arrow.png\" class=\"attachment-full size-full wp-image-1407\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/02\/arrow.png 675w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/02\/arrow-300x40.png 300w\" sizes=\"(max-width: 675px) 100vw, 675px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a8bd82 jkit-equal-height-disable elementor-widget elementor-widget-jkit_icon_box\" data-id=\"7a8bd82\" data-element_type=\"widget\" data-widget_type=\"jkit_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-icon-box icon-position- elementor-animation- jeg_module___6a044e0d9acf9\" ><div class=\"jkit-icon-box-wrapper hover-from-left\"><div class=\"icon-box icon-box-header elementor-animation-\"><div class=\"icon style-color\"><i aria-hidden=\"true\" class=\"jki jki-customer-service-light\"><\/i><\/div><\/div><div class=\"icon-box icon-box-body\">\n                <h3 class=\"title\">Choose Your Service<\/h3><p class=\"icon-box-description\">We can distribute a single product (Video Camera, microphone, etc.) or create a Broadcast solution for you. (Modern Television Center, Multifunctional event hall, etc.)\n<\/p>\n            <\/div>\n            \n            <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-29d4e24\" data-id=\"29d4e24\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3ea112 jkit-equal-height-disable elementor-widget elementor-widget-jkit_icon_box\" data-id=\"c3ea112\" data-element_type=\"widget\" data-widget_type=\"jkit_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-icon-box icon-position- elementor-animation- jeg_module__1_6a044e0d9b476\" ><div class=\"jkit-icon-box-wrapper hover-from-left\"><div class=\"icon-box icon-box-header elementor-animation-\"><div class=\"icon style-color\"><i aria-hidden=\"true\" class=\"jki jki-book1-light\"><\/i><\/div><\/div><div class=\"icon-box icon-box-body\">\n                <h3 class=\"title\">Make A Consultation<\/h3><p class=\"icon-box-description\">If you need help with your project, the Innovator's personnel experts will help you with full diligence and reliability and make an offer for you.\n\n<\/p>\n            <\/div>\n            \n            <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-966e2af elementor-widget__width-initial elementor-absolute elementor-hidden-tablet elementor-hidden-phone elementor-widget elementor-widget-image\" data-id=\"966e2af\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"90\" src=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/02\/arrow.png\" class=\"attachment-full size-full wp-image-1407\" alt=\"\" srcset=\"https:\/\/innovator.md\/wp-content\/uploads\/2023\/02\/arrow.png 675w, https:\/\/innovator.md\/wp-content\/uploads\/2023\/02\/arrow-300x40.png 300w\" sizes=\"(max-width: 675px) 100vw, 675px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-875fb5a\" data-id=\"875fb5a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a49507 jkit-equal-height-disable elementor-widget elementor-widget-jkit_icon_box\" data-id=\"2a49507\" data-element_type=\"widget\" data-widget_type=\"jkit_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-icon-box icon-position- elementor-animation- jeg_module__2_6a044e0d9bf6f\" ><div class=\"jkit-icon-box-wrapper hover-from-left\"><div class=\"icon-box icon-box-header elementor-animation-\"><div class=\"icon style-color\"><i aria-hidden=\"true\" class=\"jki jki-user-1-light\"><\/i><\/div><\/div><div class=\"icon-box icon-box-body\">\n                <h3 class=\"title\">Meet With Engineers<\/h3><p class=\"icon-box-description\">Creating a television\/radio\/studio or production company involves many steps of importance. Our technical team will help you develop and implement complex plans.\n\n<\/p>\n            <\/div>\n            \n            <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Partners Home Partners Our Partners World&#8217;s leading manufacturers representatives in Georgia Innovator is the official representative of the world&#8217;s leading manufacturers, with the legal right to distribute their products. We offer the product and service you want on the best terms; in addition, we are always ready to introduce and provide you with the latest [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/innovator.md\/ro\/wp-json\/wp\/v2\/pages\/1979"}],"collection":[{"href":"https:\/\/innovator.md\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/innovator.md\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/innovator.md\/ro\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/innovator.md\/ro\/wp-json\/wp\/v2\/comments?post=1979"}],"version-history":[{"count":112,"href":"https:\/\/innovator.md\/ro\/wp-json\/wp\/v2\/pages\/1979\/revisions"}],"predecessor-version":[{"id":4232,"href":"https:\/\/innovator.md\/ro\/wp-json\/wp\/v2\/pages\/1979\/revisions\/4232"}],"wp:attachment":[{"href":"https:\/\/innovator.md\/ro\/wp-json\/wp\/v2\/media?parent=1979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}